{"id":102309,"date":"2024-08-14T19:32:29","date_gmt":"2024-08-14T17:32:29","guid":{"rendered":"https:\/\/one-horizon.ch\/product\/orbitkey-pencil-case\/"},"modified":"2026-05-08T21:30:24","modified_gmt":"2026-05-08T19:30:24","slug":"orbitkey-pencil-case","status":"publish","type":"product","link":"https:\/\/one-horizon.ch\/fr\/product\/orbitkey-pencil-case\/","title":{"rendered":"\u00c9tui \u00e0 crayon Orbitkey"},"content":{"rendered":"<p>L&#8217;\u00e9tui \u00e0 crayon Orbitkey est plus qu&#8217;une simple trousse. Il apporte une v\u00e9ritable organisation \u00e0 votre sac &#8211; avec un syst\u00e8me bien pens\u00e9 de s\u00e9parateurs, de poches en filet et d&#8217;acc\u00e8s rapide \u00e0 ce dont vous avez besoin au quotidien. <\/p>\n<h2>Une organisation intelligente<\/h2>\n<p>Le syst\u00e8me de cloisons centrales divise judicieusement l&#8217;espace int\u00e9rieur. Des boucles \u00e9lastiques et des poches en filet maintiennent les stylos, les c\u00e2bles et les petits objets \u00e0 leur place. La poche d&#8217;acc\u00e8s rapide \u00e0 l&#8217;avant est destin\u00e9e aux objets dont vous avez besoin en permanence.  <\/p>\n<h2>Durable &amp; fonctionnel<\/h2>\n<ul>\n<li>Fabriqu\u00e9 \u00e0 partir de mat\u00e9riaux recycl\u00e9s<\/li>\n<li>Mat\u00e9riau hydrofuge et fermeture \u00e0 glissi\u00e8re<\/li>\n<li>Conception autoportante &#8211; ne se rabat pas<\/li>\n<li>Fermetures \u00e0 glissi\u00e8re basses pour une ouverture large<\/li>\n<li>Espace de rangement extensible<\/li>\n<li>Dimensions compactes : 230 \u00d7 90 \u00d7 50 mm | Poids : 68 g<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00e9tui \u00e0 stylos Orbitkey Pencil Case organise les stylos et les accessoires tech dans un espace r\u00e9duit. Design autoportant, mat\u00e9riau hydrofuge, syst\u00e8me de cloisons centrales &#8211; \u00e0 partir de mat\u00e9riaux recycl\u00e9s. 230 \u00d7 90 \u00d7 50 mm, 68 g.<\/p>\n","protected":false},"featured_media":117122,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[3032],"product_cat":[855],"product_tag":[3295,3371],"class_list":{"0":"post-102309","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-orbitkey","7":"product_cat-office-fr","8":"product_tag-pour-vous","9":"product_tag-recycle","10":"product_shipping_class-colis-jusqua-2-kg","12":"first","13":"onbackorder","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"acf":[],"_links":{"self":[{"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/product\/102309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/comments?post=102309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/media\/117122"}],"wp:attachment":[{"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/media?parent=102309"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=102309"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=102309"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=102309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}