{"id":135266,"date":"2026-07-01T21:23:41","date_gmt":"2026-07-01T19:23:41","guid":{"rendered":"https:\/\/one-horizon.ch\/product\/parapluie-bonjour-pluie-bienvenue-de-retour\/"},"modified":"2026-07-09T22:17:00","modified_gmt":"2026-07-09T20:17:00","slug":"parapluie-bonjour-pluie-bienvenue-de-retour","status":"publish","type":"product","link":"https:\/\/one-horizon.ch\/fr\/product\/parapluie-bonjour-pluie-bienvenue-de-retour\/","title":{"rendered":"Parapluie \u00ab Hello Rain Welcome Back \u00bb"},"content":{"rendered":"<p>Que la pluie tombe : avec son d\u00e9grad\u00e9 de couleurs vives, le parapluie de poche \u00ab Hello Rain, Welcome Back \u00bb transforme les journ\u00e9es maussades en v\u00e9ritables moments de joie.<\/p>\n<h2>Mat\u00e9riaux et fonctionnalit\u00e9s<\/h2>\n<p>La toile est en <strong>polyester hydrofuge<\/strong>, tandis que les baleines sont en <strong>fibre de verre<\/strong> r\u00e9sistante au vent. Gr\u00e2ce \u00e0 son bouton automatique, le parasol s&#8217;ouvre et se ferme d&#8217;une seule main. <\/p>\n<ul>\n<li><strong>Se range facilement :<\/strong> une fois repli\u00e9, le parapluie ne mesure qu&#8217;environ 29 cm et se glisse dans n&#8217;importe quel sac.<\/li>\n<li><strong>R\u00e9sistant au vent :<\/strong> les rayons en fibre de verre garantissent la stabilit\u00e9 m\u00eame en cas de rafales.<\/li>\n<\/ul>\n<h2>D\u00e9tails techniques<\/h2>\n<ul>\n<li>Dimensions (ferm\u00e9) : 29 x 6 x 6 cm<\/li>\n<li>Mat\u00e9riau : polyester, fibre de verre<\/li>\n<li>Poids : 0,35 kg<\/li>\n<li>Origine : Chine<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Parapluie de poche compact \u00ab Hello Rain, Welcome Back \u00bb aux couleurs vives d\u00e9grad\u00e9es, avec ouverture automatique. Une fois repli\u00e9, il ne mesure que 29 cm de long ; il est fabriqu\u00e9 en polyester hydrofuge et dot\u00e9 de baleines en fibre de verre r\u00e9sistantes au vent. Le compagnon id\u00e9al pour les jours de pluie.  <\/p>\n","protected":false},"featured_media":135238,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_oh_fbt_bundles_id":[],"_oh_season":"year-round"},"product_brand":[4057],"product_cat":[3532],"product_tag":[],"class_list":["post-135266","product","type-product","status-publish","has-post-thumbnail","product_brand-fissure","product_cat-parapluies","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/product\/135266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/comments?post=135266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/media\/135238"}],"wp:attachment":[{"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/media?parent=135266"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=135266"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=135266"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/one-horizon.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=135266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}